{"id":987490553,"date":"2023-02-06T12:13:48","date_gmt":"2023-02-06T12:13:48","guid":{"rendered":"https:\/\/veronaintour.com\/tour\/dulce-lessinia-senderismo\/"},"modified":"2024-02-22T12:47:54","modified_gmt":"2024-02-22T12:47:54","slug":"dulce-lessinia-senderismo","status":"publish","type":"tour","link":"https:\/\/veronaintour.com\/es\/tour\/dulce-lessinia-senderismo\/","title":{"rendered":"Dulce Lessinia Senderismo"},"content":{"rendered":"<p>[et_pb_section fb_built=\u00bb1&#8243; _builder_version=\u00bb4.20.4&#8243; _module_preset=\u00bbdefault\u00bb custom_padding=\u00bb||0px|||\u00bb locked=\u00bboff\u00bb global_colors_info=\u00bb{}\u00bb theme_builder_area=\u00bbpost_content\u00bb][et_pb_row use_custom_gutter=\u00bbon\u00bb gutter_width=\u00bb1&#8243; module_class=\u00bbcol-width\u00bb _builder_version=\u00bb4.20.4&#8243; _module_preset=\u00bbdefault\u00bb custom_margin=\u00bb0px||0px||true|false\u00bb custom_padding=\u00bb0px||0px||true|false\u00bb global_colors_info=\u00bb{}\u00bb theme_builder_area=\u00bbpost_content\u00bb][et_pb_column type=\u00bb4_4&#8243; _builder_version=\u00bb4.20.4&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb theme_builder_area=\u00bbpost_content\u00bb][et_pb_gallery gallery_ids=\u00bb987490221,987490217,987490225,987490213&#8243; show_title_and_caption=\u00bboff\u00bb show_pagination=\u00bboff\u00bb zoom_icon_color=\u00bbRGBA(255,255,255,0)\u00bb hover_overlay_color=\u00bbRGBA(255,255,255,0)\u00bb module_class=\u00bbcol-width\u00bb _builder_version=\u00bb4.20.4&#8243; _module_preset=\u00bbdefault\u00bb border_color_all=\u00bb#FFFFFF\u00bb border_width_all_image=\u00bb4px\u00bb border_color_all_image=\u00bb#FFFFFF\u00bb global_colors_info=\u00bb{}\u00bb theme_builder_area=\u00bbpost_content\u00bb][\/et_pb_gallery][\/et_pb_column][\/et_pb_row][\/et_pb_section][et_pb_section fb_built=\u00bb1&#8243; _builder_version=\u00bb4.20.4&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb theme_builder_area=\u00bbpost_content\u00bb][et_pb_row column_structure=\u00bb1_2,1_2&#8243; _builder_version=\u00bb4.20.4&#8243; _module_preset=\u00bbdefault\u00bb custom_padding=\u00bb0px||||false|false\u00bb global_colors_info=\u00bb{}\u00bb theme_builder_area=\u00bbpost_content\u00bb][et_pb_column type=\u00bb1_2&#8243; _builder_version=\u00bb4.16&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb theme_builder_area=\u00bbpost_content\u00bb][et_pb_text _builder_version=\u00bb4.20.4&#8243; custom_margin=\u00bb||10px||false|false\u00bb custom_padding=\u00bb||||false|false\u00bb locked=\u00bboff\u00bb global_colors_info=\u00bb{}\u00bb theme_builder_area=\u00bbpost_content\u00bb]<\/p>\n<h3>Descripci\u00f3n<\/h3>\n<p>Cuatro d\u00edas de agradable y relajante senderismo, apto para toda la familia, para descubrir la naturaleza, los paisajes, la artesan\u00eda y los sabores de la zona en el Parque Natural Regional de Lessinia.<\/p>\n<p>Partiendo de Borgochiesanuova, la ruta sigue antiguos senderos que conectan pueblos y refugios de monta\u00f1a de la zona, proporcionando al viajero todo el placer de una inmersi\u00f3n a ritmo lento en la naturaleza.<\/p>\n<p>El recorrido serpentea por pastos y miradores que van desde el valle del Po a los Apeninos, el lago de Garda y los Dolomitas y sigue, en peque\u00f1a medida, el sendero E5, que va de Venecia a Breta\u00f1a, creando uno de los caminos m\u00e1s famosos de la red de senderos europeos.<\/p>\n<p>Las distintas etapas alternan agradables paseos con momentos de relax, experiencias para descubrir la artesan\u00eda y las tradiciones con apasionantes degustaciones de productos t\u00edpicos.[\/et_pb_text][\/et_pb_column][et_pb_column type=\u00bb1_2&#8243; _builder_version=\u00bb4.16&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb theme_builder_area=\u00bbpost_content\u00bb][et_pb_text _builder_version=\u00bb4.20.4&#8243; custom_margin=\u00bb||10px||false|false\u00bb custom_padding=\u00bb||||false|false\u00bb locked=\u00bboff\u00bb global_colors_info=\u00bb{}\u00bb theme_builder_area=\u00bbpost_content\u00bb]<\/p>\n<h3>Itinerario<\/h3>\n<p>[\/et_pb_text][et_pb_accordion open_toggle_text_color=\u00bb#2a2e31&#8243; open_toggle_background_color=\u00bb#efefef\u00bb closed_toggle_text_color=\u00bb#2a2e31&#8243; closed_toggle_background_color=\u00bb#efefef\u00bb icon_color=\u00bb#cb3c3b\u00bb use_icon_font_size=\u00bbon\u00bb icon_font_size=\u00bb14px\u00bb _builder_version=\u00bb4.20.4&#8243; _module_preset=\u00bbdefault\u00bb toggle_text_color=\u00bb#2a2e31&#8243; toggle_font=\u00bb||||||||\u00bb toggle_font_size=\u00bb18px\u00bb toggle_line_height=\u00bb1.3em\u00bb custom_padding=\u00bb||||false|false\u00bb toggle_font_size_tablet=\u00bb18px\u00bb toggle_font_size_phone=\u00bb17px\u00bb toggle_font_size_last_edited=\u00bbon|desktop\u00bb border_width_all=\u00bb0px\u00bb locked=\u00bboff\u00bb global_colors_info=\u00bb{}\u00bb theme_builder_area=\u00bbpost_content\u00bb][et_pb_accordion_item title=\u00bbSu t\u00edtulo va aqu\u00ed\u00bb open=\u00bbon\u00bb _builder_version=\u00bb4.20.4&#8243; _module_preset=\u00bbdefault\u00bb custom_css_main_element=\u00bbdisplay: none!important\u00bb global_colors_info=\u00bb{}\u00bb theme_builder_area=\u00bbpost_content\u00bb]<\/p>\n<p>Su contenido va aqu\u00ed. Edite o elimine este texto en l\u00ednea o en la configuraci\u00f3n de Contenido del m\u00f3dulo. Tambi\u00e9n puede dar estilo a cada aspecto de este contenido en la configuraci\u00f3n de dise\u00f1o del m\u00f3dulo e incluso aplicar CSS personalizado a este texto en la configuraci\u00f3n avanzada del m\u00f3dulo.<\/p>\n<p>[\/et_pb_accordion_item][et_pb_accordion_item title=\u00bbD\u00eda 1 &#8211; Boscochiesanuova &#8211; Contrada laorno\u00bb _builder_version=\u00bb4.20.4&#8243; _module_preset=\u00bbdefault\u00bb custom_margin=\u00bb15px||15px||true|false\u00bb custom_padding=\u00bb15px||15px||true|false\u00bb global_colors_info=\u00bb{}\u00bb custom_margin__hover_enabled=\u00bbon|desktop\u00bb custom_margin__hover=\u00bb15px||15px||true|false\u00bb theme_builder_area=\u00bbpost_content\u00bb open=\u00bboff\u00bb]Salida desde Boscochiesanuova para una caminata de intensidad media de aproximadamente 1 hora y 30 minutos. La ruta, con una ligera subida inicial, discurre por pastos rodeados de naturaleza. El camino conduce al barrio de Laorno, una cervecer\u00eda agr\u00edcola, un lugar m\u00e1gico donde se respira silencio y se disfruta de la brisa del hayedo. Visita de la f\u00e1brica y degustaci\u00f3n de cerveza acompa\u00f1ada de una tabla de embutidos y quesos. Alojamiento en las habitaciones y cena de productos t\u00edpicos de Lessinia. Pasar la noche.[\/et_pb_accordion_item][et_pb_accordion_item title=\u00bbD\u00eda 2 &#8211; Contrada Laorno &#8211; Localit\u00e0 Castelberto\u00bb _builder_version=\u00bb4.20.4&#8243; _module_preset=\u00bbdefault\u00bb custom_margin=\u00bb15px||15px||true|false\u00bb custom_padding=\u00bb15px||15px||true|false\u00bb global_colors_info=\u00bb{}\u00bb custom_margin__hover_enabled=\u00bbon|desktop\u00bb custom_margin__hover=\u00bb15px||15px||true|false\u00bb theme_builder_area=\u00bbpost_content\u00bb open=\u00bboff\u00bb]Desayuno y salida para una caminata f\u00e1cil de 4 horas, apta para toda la familia: uno de los senderos m\u00e1s bellos de toda la Lessinia a caballo entre la frontera del V\u00e9neto y el Trentino, un lugar de gran importancia tanto hist\u00f3rica como natural\u00edstica. La vista es maravillosa: las cumbres del Trentino, Val d&#8217;Adige, Valpolicella y el lago de Garda, el Monte Baldo y toda Lessinia. La ruta serpentea entre pastos y caba\u00f1as dentro del parque natural regional y llega a Castelberto, a 1.765 m de altitud, punto terminal de la meseta. El refugio es una fiel reconstrucci\u00f3n de un edificio militar de la Primera Guerra Mundial y en las inmediaciones a\u00fan quedan restos de antiguas trincheras que datan de la Gran Guerra. Rodeados de la belleza de las monta\u00f1as, podemos admirar un fant\u00e1stico panorama y disfrutar de una cocina t\u00edpica compuesta por platos tradicionales de la regi\u00f3n del V\u00e9neto. Cena y alojamiento en el refugio.[\/et_pb_accordion_item][et_pb_accordion_item title=\u00bbD\u00eda 3 &#8211; Localit\u00e0 Castelberto &#8211; Rifugio Alpino Dardo\u00bb _builder_version=\u00bb4.20.4&#8243; _module_preset=\u00bbdefault\u00bb custom_margin=\u00bb15px||15px||true|false\u00bb custom_padding=\u00bb15px||15px||true|false\u00bb global_colors_info=\u00bb{}\u00bb custom_margin__hover_enabled=\u00bbon|desktop\u00bb custom_margin__hover=\u00bb15px||15px||true|false\u00bb theme_builder_area=\u00bbpost_content\u00bb open=\u00bboff\u00bb]Despu\u00e9s de desayunar salimos del refugio para llegar, con un corto paseo, a una de las caba\u00f1as m\u00e1s famosas de Lessinia. Vivir\u00e1 una experiencia espl\u00e9ndida descubriendo los secretos de la producci\u00f3n del queso de monta\u00f1a. Despu\u00e9s continuaremos con un sencillo trekking por el malghe para llegar al destino del d\u00eda: el refugio del Dardo, un peque\u00f1o rinc\u00f3n del para\u00edso donde a\u00fan es posible encontrar los sabores genuinos de Lessinia. Aqu\u00ed los colores, los perfumes y los silencios se mezclan dando un panorama sobrecogedor. Un lugar ideal para la familia donde alrededor de una mesa se puede disfrutar de \u00f1oquis de malga, alb\u00f3ndigas de ricotta y espinacas, lasagnette con rag\u00fa de setas o trufa y deliciosos postres caseros. Cena y alojamiento.[\/et_pb_accordion_item][et_pb_accordion_item title=\u00bbD\u00eda 4 &#8211; Rifugio Alpino Dardo &#8211; Localit\u00e0 Ongar\u00bb _builder_version=\u00bb4.20.4&#8243; _module_preset=\u00bbdefault\u00bb custom_margin=\u00bb15px||15px||true|false\u00bb custom_padding=\u00bb15px||15px||true|false\u00bb global_colors_info=\u00bb{}\u00bb custom_margin__hover_enabled=\u00bbon|desktop\u00bb custom_margin__hover=\u00bb15px||15px||true|false\u00bb theme_builder_area=\u00bbpost_content\u00bb open=\u00bboff\u00bb]Despu\u00e9s del desayuno, entre hayas y pastos libres, recorreremos una peque\u00f1a parte del sendero E5, uno de los m\u00e1s famosos de Europa que serpentea de Venecia a Breta\u00f1a. La llegada de nuestra ruta es una maravillosa zona verde en un antiguo barrio del 1700, completamente renovado y transformado en un alojamiento r\u00fastico y refinado que ofrece una piscina y un spa para relajarse al final del viaje. Tarde libre y cena en el hotel. Pasar la noche.[\/et_pb_accordion_item][et_pb_accordion_item title=\u00bbD\u00eda 5 &#8211; Localit\u00e0 Ongar &#8211; Bosco Chiesanuova\u00bb _builder_version=\u00bb4.20.4&#8243; _module_preset=\u00bbdefault\u00bb custom_margin=\u00bb15px||15px||true|false\u00bb custom_padding=\u00bb15px||15px||true|false\u00bb global_colors_info=\u00bb{}\u00bb custom_margin__hover_enabled=\u00bbon|desktop\u00bb custom_margin__hover=\u00bb15px||15px||true|false\u00bb theme_builder_area=\u00bbpost_content\u00bb open=\u00bboff\u00bb]El desayuno. Con un agradable paseo de unos 30 minutos se llega a la aldea de Bosco Chiesanuova y al punto de encuentro, el punto final de la caminata.[\/et_pb_accordion_item][\/et_pb_accordion][\/et_pb_column][\/et_pb_row][et_pb_row column_structure=\u00bb1_2,1_2&#8243; _builder_version=\u00bb4.20.4&#8243; _module_preset=\u00bbdefault\u00bb locked=\u00bboff\u00bb global_colors_info=\u00bb{}\u00bb theme_builder_area=\u00bbpost_content\u00bb][et_pb_column type=\u00bb1_2&#8243; _builder_version=\u00bb4.20.4&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb theme_builder_area=\u00bbpost_content\u00bb][et_pb_tabs active_tab_background_color=\u00bb#cb3c3b\u00bb inactive_tab_background_color=\u00bb#efefef\u00bb active_tab_text_color=\u00bb#FFFFFF\u00bb module_class=\u00bbequal-tabs\u00bb _builder_version=\u00bb4.24.2&#8243; _module_preset=\u00bbdefault\u00bb tab_text_color=\u00bb#2a2e31&#8243; tab_line_height=\u00bb1.3em\u00bb custom_margin=\u00bb||||false|false\u00bb custom_padding=\u00bb|0px||0px|false|true\u00bb hover_enabled=\u00bb0&#8243; border_width_all=\u00bb0px\u00bb locked=\u00bboff\u00bb global_colors_info=\u00bb{}\u00bb theme_builder_area=\u00bbpost_content\u00bb sticky_enabled=\u00bb0&#8243;][et_pb_tab title=\u00bbTour info\u00bb _builder_version=\u00bb4.24.2&#8243; _module_preset=\u00bbdefault\u00bb hover_enabled=\u00bb0&#8243; global_colors_info=\u00bb{}\u00bb theme_builder_area=\u00bbpost_content\u00bb sticky_enabled=\u00bb0&#8243;]<\/p>\n<p><strong>M23001 &#8211; Tour privado<\/strong><\/p>\n<p><strong>Precios<\/strong>: a <span>consultar<\/span><br \/><strong>Duraci\u00f3n<\/strong> del viaje: 5 d\u00edas \/ 4 noches<br \/><strong>Distancia total<\/strong>: unos 25 km<\/p>\n<p><strong>Edad m\u00ednima:<\/strong> apto para adultos y ni\u00f1os capaces de caminar por senderos ondulados durante el tiempo previsto por las etapas del trekking.<\/p>\n<p>Este itinerario incluye viajes por sus propios medios y puede personalizarse para adaptarlo a sus necesidades.<\/p>\n<p>Obtenga respuesta a sus preguntas. Lea las <a title=\"Preguntas frecuentes\" href=\"https:\/\/veronaintour.com\/es\/faqs\/\" target=\"_blank\" rel=\"noopener\">FAQ<\/a> para encontrar respuesta a las preguntas m\u00e1s frecuentes o p\u00f3ngase en contacto con nosotros a trav\u00e9s del siguiente formulario.<\/p>\n<p>[\/et_pb_tab][et_pb_tab title=\u00bbIncluye\u00bb _builder_version=\u00bb4.20.4&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb theme_builder_area=\u00bbpost_content\u00bb]<\/p>\n<ul>\n<li>Briefing de bienvenida y entrega del equipo de trekking<\/li>\n<li>4 noches con desayuno incluido:<\/li>\n<li>4 cenas seg\u00fan lo previsto<\/li>\n<li>Experiencia \u00abDe la leche al queso\u00bb en un refugio de monta\u00f1a<\/li>\n<\/ul>\n<p>[\/et_pb_tab][et_pb_tab title=\u00bbNo incluido\u00bb _builder_version=\u00bb4.20.4&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb theme_builder_area=\u00bbpost_content\u00bb]<\/p>\n<ul>\n<li>Tasa tur\u00edstica a pagar directamente in situ<\/li>\n<li>Seguro de viaje<\/li>\n<li>Todas las comidas no mencionadas en el itinerario<\/li>\n<li>Aparcamiento en Borgochiesanuova<\/li>\n<li>Gastos personales y todo lo no mencionado en el apartado \u00abEl viaje incluye\u00bb<\/li>\n<\/ul>\n<p>[\/et_pb_tab][\/et_pb_tabs][\/et_pb_column][et_pb_column type=\u00bb1_2&#8243; _builder_version=\u00bb4.20.4&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb theme_builder_area=\u00bbpost_content\u00bb][et_pb_text _builder_version=\u00bb4.20.4&#8243; _module_preset=\u00bbdefault\u00bb custom_margin=\u00bb||10px||false|false\u00bb custom_padding=\u00bb||||false|false\u00bb locked=\u00bboff\u00bb global_colors_info=\u00bb{}\u00bb theme_builder_area=\u00bbpost_content\u00bb]<\/p>\n<h3>Cont\u00e1ctanos<\/h3>\n<p>[\/et_pb_text][dvppl_cf7_styler cf7=\u00bb987492348&#8243; form_field_padding=\u00bb15px|10px|15px|10px|true|true\u00bb _builder_version=\u00bb4.24.0&#8243; _module_preset=\u00bbdefault\u00bb form_field_font_text_color=\u00bb#2a2e31&#8243; form_field_font_font_size=\u00bb16px\u00bb custom_submit_button=\u00bbon\u00bb submit_button_text_size=\u00bb16px\u00bb submit_button_text_color=\u00bb#FFFFFF\u00bb submit_button_bg_color=\u00bb#cb3c3b\u00bb submit_button_border_color=\u00bb#cb3c3b\u00bb submit_button_border_radius=\u00bb3px\u00bb submit_button_font=\u00bb|||on|||||\u00bb submit_button_custom_padding=\u00bb12px|30px|12px|30px|true|true\u00bb submit_button_letter_spacing_last_edited=\u00bboff|desktop\u00bb border_color_all_field=\u00bbRGBA(255,255,255,0)\u00bb locked=\u00bboff\u00bb global_colors_info=\u00bb{}\u00bb submit_button_letter_spacing__hover_enabled=\u00bbon|hover\u00bb submit_button_letter_spacing__hover=\u00bb1px\u00bb theme_builder_area=\u00bbpost_content\u00bb][\/dvppl_cf7_styler][\/et_pb_column][\/et_pb_row][\/et_pb_section]<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Una ruta de senderismo entre naturaleza, bosques y bosques para descubrir fauna y flora con un viaje apto para todos los que visitan el Parque Natural Regional de Lessinia.<\/p>\n","protected":false},"author":1,"featured_media":987488643,"template":"","format":"standard","meta":{"_et_pb_use_builder":"on","_et_pb_old_content":"","_et_gb_content_width":""},"class_list":["post-987490553","tour","type-tour","status-publish","format-standard","has-post-thumbnail","hentry"],"_links":{"self":[{"href":"https:\/\/veronaintour.com\/es\/wp-json\/wp\/v2\/tour\/987490553","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/veronaintour.com\/es\/wp-json\/wp\/v2\/tour"}],"about":[{"href":"https:\/\/veronaintour.com\/es\/wp-json\/wp\/v2\/types\/tour"}],"author":[{"embeddable":true,"href":"https:\/\/veronaintour.com\/es\/wp-json\/wp\/v2\/users\/1"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/veronaintour.com\/es\/wp-json\/wp\/v2\/media\/987488643"}],"wp:attachment":[{"href":"https:\/\/veronaintour.com\/es\/wp-json\/wp\/v2\/media?parent=987490553"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}